{"id":7787,"date":"2023-06-20T10:39:54","date_gmt":"2023-06-20T10:39:54","guid":{"rendered":"https:\/\/solardrone.es\/termografia-fotovoltaica-con-i-droni\/"},"modified":"2024-12-02T13:45:04","modified_gmt":"2024-12-02T13:45:04","slug":"termografia-fotovoltaica-con-i-droni","status":"publish","type":"page","link":"https:\/\/solardrone.es\/it\/servizi\/termografia-fotovoltaica-con-i-droni\/","title":{"rendered":"Termografia fotovoltaica con i droni"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7787\" class=\"elementor elementor-7787 elementor-2\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-341f8394 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"341f8394\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3c9c20bd\" data-id=\"3c9c20bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dc4174 e-transform elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2dc4174\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInDown&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">La tranquillit\u00e0 di avere ogni modulo sotto controllo<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fb92d24 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4fb92d24\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Termografia fotovoltaica con i droni<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49f3998e animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"49f3998e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"color: #333333;\">Volo + piattaforma web + AI. <strong>Termografia con droni<\/strong> per rilevare il 100% dei difetti nei moduli fotovoltaici e sapere in meno di 1 minuto come intervenire affinch\u00e9 il tuo impianto generi pi\u00f9 energia.<\/span><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-515db4f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"515db4f9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-33604af\" data-id=\"33604af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca9ea69 elementor-widget elementor-widget-html\" data-id=\"ca9ea69\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- Google Calendar Appointment Scheduling begin -->\n<link href=\"https:\/\/calendar.google.com\/calendar\/scheduling-button-script.css\" rel=\"stylesheet\">\n<script src=\"https:\/\/calendar.google.com\/calendar\/scheduling-button-script.js\" async=\"\"><\/script>\n<script>\n(function() {\n  var target = document.currentScript;\n  window.addEventListener('load', function() {\n    calendar.schedulingButton.load({\n      url: 'https:\/\/calendar.google.com\/calendar\/appointments\/schedules\/AcZssZ1OM0jl_x3X0YiMRZtN0IyT1RGRs0iAP6coJgkhSx1CwtNHpjAYAcxlENEgtgoC44TADcXH6l7p?gv=true',\n      color: '#3636b6',\n      label: 'AGENDA TU DEMO > ',\n      target,\n    });\n  });\n})();\n<\/script>\n<!-- end Google Calendar Appointment Scheduling -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-595b81cc\" data-id=\"595b81cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-432fa12 elementor-widget elementor-widget-image\" data-id=\"432fa12\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/07\/Solardrone-pcPortadaWeb-sombra-min-1.png\" class=\"attachment-full size-full wp-image-4284\" alt=\"\" srcset=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/07\/Solardrone-pcPortadaWeb-sombra-min-1.png 800w, https:\/\/solardrone.es\/wp-content\/uploads\/2023\/07\/Solardrone-pcPortadaWeb-sombra-min-1-300x200.png 300w, https:\/\/solardrone.es\/wp-content\/uploads\/2023\/07\/Solardrone-pcPortadaWeb-sombra-min-1-768x512.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b157c7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b157c7c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-faca154\" data-id=\"faca154\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d9c87e elementor-widget elementor-widget-heading\" data-id=\"9d9c87e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">I leader del settore utilizzano gi\u00e0 la termografia fotovoltaica per la cura dei moduli<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af96aa0 elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"af96aa0\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;dots&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;speed&quot;:700,&quot;autoplay_speed&quot;:900,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2024\/06\/49OG9I4gHwmfBHotGqC4hFMGlE31718009520154_200x200.png\" alt=\"49OG9I4gHwmfBHotGqC4hFMGlE31718009520154_200x200\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/09\/2560px-Veolia_logo.svg-300x75.png\" alt=\"2560px-Veolia_logo.svg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/09\/engie_2021-300x300.png\" alt=\"engie_2021\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2024\/10\/OHLA-300x156.png\" alt=\"OHLA\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/09\/SONNEDIX-logo-color-300x153.png\" alt=\"SONNEDIX-logo-color\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2024\/06\/TUV_SUD_logo_rebrand-300x300.png\" alt=\"TUV_SUD_logo_rebrand\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2024\/06\/tuev_rheinland_logo_core_4_3-300x225.jpg\" alt=\"tuev_rheinland_logo_core_4_3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/09\/logo-rios-renovables-1.png\" alt=\"logo rios renovables 1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2024\/06\/alterna_energia_logo.jpeg\" alt=\"alterna_energia_logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2024\/06\/acisa-300x173.jpeg\" alt=\"acisa\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/09\/plenium-partners-logo.png\" alt=\"plenium-partners-logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/09\/cropped-LOGOTIPOS-QUALITAS-ENERGY_V2-11-300x133.png\" alt=\"cropped-LOGOTIPOS-QUALITAS-ENERGY_V2-11\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/09\/cropped-cropped-logo-1-300x71.png\" alt=\"cropped-cropped-logo-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/09\/juntos-mejor.png\" alt=\"juntos-mejor\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/09\/levitec-logo.png\" alt=\"levitec-logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/09\/logo-300x77.png\" alt=\"logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/09\/Logo-Soltec-Horizontal-CMYK-GR-BLUE-300x106.png\" alt=\"Logo-Soltec-Horizontal-CMYK-GR-BLUE\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 di 18\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/09\/image-3.png\" alt=\"image (3)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-968743d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"968743d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4d1998f\" data-id=\"4d1998f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b954820 elementor-widget elementor-widget-counter\" data-id=\"b954820\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Piante analizzate<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"700\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e479e54\" data-id=\"e479e54\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d108778 elementor-widget elementor-widget-counter\" data-id=\"d108778\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Paesi con capacit\u00e0 operativa<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"20\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e65e56e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e65e56e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-00f6729\" data-id=\"00f6729\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0480a7c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"0480a7c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Evita il costo di non rendersi conto che sta accadendo qualcosa di importante.<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b06cc0 elementor-widget elementor-widget-text-editor\" data-id=\"5b06cc0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>I sistemi di monitoraggio dell&#8217;impianto rilevano i problemi solo a livello di stringa, non a livello di modulo. Ci\u00f2 significa che centinaia di moduli fotovoltaici sparsi per l&#8217;impianto presentano difetti\/perdite non rilevati che potrebbero comprometterne la redditivit\u00e0 e la durata. <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f29161f elementor-widget elementor-widget-html\" data-id=\"f29161f\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- Google Calendar Appointment Scheduling begin -->\n<div style=\"display: flex; justify-content: center; margin: 0px 0;\">\n  <link href=\"https:\/\/calendar.google.com\/calendar\/scheduling-button-script.css\" rel=\"stylesheet\">\n  <script src=\"https:\/\/calendar.google.com\/calendar\/scheduling-button-script.js\" async=\"\"><\/script>\n  <script>\n  (function() {\n    var target = document.currentScript;\n    window.addEventListener('load', function() {\n      calendar.schedulingButton.load({\n        url: 'https:\/\/calendar.google.com\/calendar\/appointments\/schedules\/AcZssZ1OM0jl_x3X0YiMRZtN0IyT1RGRs0iAP6coJgkhSx1CwtNHpjAYAcxlENEgtgoC44TADcXH6l7p?gv=true',\n        color: '#3636b6',\n        label: 'AGENDA TU DEMO',\n        target,\n      });\n    });\n  })();\n  <\/script>\n<\/div>\n<!-- end Google Calendar Appointment Scheduling -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9980455 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9980455\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9d96cee\" data-id=\"9d96cee\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e4a2d9 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"7e4a2d9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><span style=\"color: var( --e-global-color-primary );background-color: var( --e-global-color-855cafa )\">IEC 62446-3 + <\/span>scudo termico + visuale + IA\n<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-895830d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"895830d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Termografia fotovoltaica con qualit\u00e0 IEC + certificazione al 100% dei moduli analizzati.<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cbd786 elementor-widget elementor-widget-text-editor\" data-id=\"6cbd786\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight ); background-color: var( --e-global-color-855cafa );\">Digitalizziamo il tuo impianto, mappandolo termicamente e visivamente, per garantire che tutti i moduli siano analizzati e ben diagnosticati grazie ai nostri esperti coinvolti nell&#8217;IEC.<\/span><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9a2ba6 elementor-widget elementor-widget-image\" data-id=\"d9a2ba6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"305\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/10\/mapas-termicos-1024x390.jpeg\" class=\"attachment-large size-large wp-image-5883\" alt=\"termografia con drones\" srcset=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/10\/mapas-termicos-1024x390.jpeg 1024w, https:\/\/solardrone.es\/wp-content\/uploads\/2023\/10\/mapas-termicos-300x114.jpeg 300w, https:\/\/solardrone.es\/wp-content\/uploads\/2023\/10\/mapas-termicos-768x293.jpeg 768w, https:\/\/solardrone.es\/wp-content\/uploads\/2023\/10\/mapas-termicos-1536x585.jpeg 1536w, https:\/\/solardrone.es\/wp-content\/uploads\/2023\/10\/mapas-termicos.jpeg 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29b2ad8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29b2ad8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b8fbb6f\" data-id=\"b8fbb6f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7ce308 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f7ce308\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Posizione affidabile al 100%<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8083099 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8083099\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Soluzioni semplici per il tuo team<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bbad3f elementor-widget elementor-widget-text-editor\" data-id=\"8bbad3f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Effettuare azioni correttive fino a due volte pi\u00f9 velocemente grazie al fatto che ogni modulo del report generato \u00e8 localizzato con precisione nel layout ufficiale dell&#8217;impianto.<\/p>\n<p>Ci\u00f2 \u00e8 possibile grazie alla tecnologia GPS RTK (precisione di 1-2 cm) combinata con la mappatura termica. Entrambe garantiscono una localizzazione precisa di ogni modulo, sia GPS che di riga e colonna.   <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c154aa elementor-widget elementor-widget-image\" data-id=\"5c154aa\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"254\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2024\/01\/467f88cf002b87401a29598ab512937ca44a5d537cf3b112adfe7440df4c55b9-I-300x254.png\" class=\"attachment-medium size-medium wp-image-6454\" alt=\"\" srcset=\"https:\/\/solardrone.es\/wp-content\/uploads\/2024\/01\/467f88cf002b87401a29598ab512937ca44a5d537cf3b112adfe7440df4c55b9-I-300x254.png 300w, https:\/\/solardrone.es\/wp-content\/uploads\/2024\/01\/467f88cf002b87401a29598ab512937ca44a5d537cf3b112adfe7440df4c55b9-I.png 730w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03bf1c1 elementor-widget elementor-widget-html\" data-id=\"03bf1c1\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- Google Calendar Appointment Scheduling begin -->\n<div style=\"display: flex; justify-content: center; margin: 0px 0;\">\n  <link href=\"https:\/\/calendar.google.com\/calendar\/scheduling-button-script.css\" rel=\"stylesheet\">\n  <script src=\"https:\/\/calendar.google.com\/calendar\/scheduling-button-script.js\" async=\"\"><\/script>\n  <script>\n  (function() {\n    var target = document.currentScript;\n    window.addEventListener('load', function() {\n      calendar.schedulingButton.load({\n        url: 'https:\/\/calendar.google.com\/calendar\/appointments\/schedules\/AcZssZ1OM0jl_x3X0YiMRZtN0IyT1RGRs0iAP6coJgkhSx1CwtNHpjAYAcxlENEgtgoC44TADcXH6l7p?gv=true',\n        color: '#3636b6',\n        label: 'AGENDA TU DEMO',\n        target,\n      });\n    });\n  })();\n  <\/script>\n<\/div>\n<!-- end Google Calendar Appointment Scheduling -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c6ee20 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c6ee20\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-92ea19b\" data-id=\"92ea19b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f435e3 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"3f435e3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">termografia con drone di qualit\u00e0<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8176685 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8176685\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Zero rumore, solo coraggio<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-802ede7 elementor-widget elementor-widget-text-editor\" data-id=\"802ede7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ti mostriamo lo stato completo dell&#8217;impianto, ma ti guidiamo a filtrare le informazioni davvero importanti. Il nostro obiettivo \u00e8 che tu capisca lo stato reale dell&#8217;impianto in 1 minuto e sappia dove e come agire senza perdere tempo. <\/p>\n<p>Inoltre, grazie ai big data anonimizzati, ti mostriamo lo stato del tuo impianto rispetto ad altri impianti simili.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb03e34 elementor-widget elementor-widget-image\" data-id=\"eb03e34\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"219\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2024\/01\/27950619ae7e772ee6b32b3db2fbcba94ffc4aa88b4bf4795c0518817611eaa7-I-e1705832154867-1024x280.png\" class=\"attachment-large size-large wp-image-6352\" alt=\"\" srcset=\"https:\/\/solardrone.es\/wp-content\/uploads\/2024\/01\/27950619ae7e772ee6b32b3db2fbcba94ffc4aa88b4bf4795c0518817611eaa7-I-e1705832154867-1024x280.png 1024w, https:\/\/solardrone.es\/wp-content\/uploads\/2024\/01\/27950619ae7e772ee6b32b3db2fbcba94ffc4aa88b4bf4795c0518817611eaa7-I-e1705832154867-300x82.png 300w, https:\/\/solardrone.es\/wp-content\/uploads\/2024\/01\/27950619ae7e772ee6b32b3db2fbcba94ffc4aa88b4bf4795c0518817611eaa7-I-e1705832154867-768x210.png 768w, https:\/\/solardrone.es\/wp-content\/uploads\/2024\/01\/27950619ae7e772ee6b32b3db2fbcba94ffc4aa88b4bf4795c0518817611eaa7-I-e1705832154867.png 1288w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2d2c3f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2d2c3f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8712640\" data-id=\"8712640\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77a6154 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"77a6154\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Previsione dell'intelligenza artificiale  <\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae1c74b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ae1c74b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Termografia fotovoltaica con droni artificialmente intelligenti<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7dc2c7 elementor-widget elementor-widget-text-editor\" data-id=\"e7dc2c7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Rivela non solo lo stato attuale dell&#8217;impianto, ma anche l&#8217;evoluzione dei moduli nel tempo (tasso di degrado) grazie agli strumenti di visualizzazione temporale.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49ee08d elementor-widget elementor-widget-html\" data-id=\"49ee08d\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- Google Calendar Appointment Scheduling begin -->\n<link href=\"https:\/\/calendar.google.com\/calendar\/scheduling-button-script.css\" rel=\"stylesheet\">\n<script src=\"https:\/\/calendar.google.com\/calendar\/scheduling-button-script.js\" async=\"\"><\/script>\n<script>\n(function() {\n  var target = document.currentScript;\n  window.addEventListener('load', function() {\n    calendar.schedulingButton.load({\n      url: 'https:\/\/calendar.google.com\/calendar\/appointments\/schedules\/AcZssZ1OM0jl_x3X0YiMRZtN0IyT1RGRs0iAP6coJgkhSx1CwtNHpjAYAcxlENEgtgoC44TADcXH6l7p?gv=true',\n      color: '#3636b6',\n      label: 'AGENDA TU DEMO',\n      target,\n    });\n  });\n})();\n<\/script>\n<!-- end Google Calendar Appointment Scheduling -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76274f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76274f8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1571a8f\" data-id=\"1571a8f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79baa08 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"79baa08\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Confronto Solardrone.ai vs Concorrenza<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72587df elementor-widget elementor-widget-text-editor\" data-id=\"72587df\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>L&#8217;apparecchiatura segue la norma TS IEC-62446-3, ma ci sono altri punti che riteniamo essenziali per garantire una buona analisi termografica:<\/p>\n<ul>\n<li><b>Certificazione 100% moduli testati<\/b>. Non \u00e8 obbligatorio secondo gli standard IEC, ma riteniamo fondamentale garantire che tutti i moduli siano testati. Ci\u00f2 \u00e8 possibile grazie alla tecnologia di mappatura termica (ortomosaico).  <\/li>\n<li><b>Certificazione 100% ben classificata<\/b>. Inoltre non \u00e8 obbligatoria secondo l&#8217;IEC. I droni generano circa 6000 immagini per MWp e l&#8217;errore umano pu\u00f2 superare il 10%. Per evitare questo problema, Solardrone utilizza modelli di classificazione automatica che sfruttano il deep learning per ridurre il tasso di errore a meno del 2%.   <\/li>\n<li><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif;\"><b>Certificazione di localizzazione accurata al 100%<\/b><\/span><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\"><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">In questo modo si evitano i problemi di localizzazione dei moduli sul campo. Ci\u00f2 \u00e8 possibile grazie all&#8217;uso del GPS RTK e della mappatura termica. <\/span><\/span>\n<\/p>\n<\/li>\n<\/ul>\n<div>Termografia con droni di qualit\u00e0 garantita. L&#8217;unica piattaforma sul mercato che include la mappa termica (ortomosaico) + gli standard IEC + IA. <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2de2a27 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"2de2a27\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1222\" height=\"629\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2024\/03\/Benchmark_OK.jpg\" class=\"attachment-full size-full wp-image-6894\" alt=\"\" srcset=\"https:\/\/solardrone.es\/wp-content\/uploads\/2024\/03\/Benchmark_OK.jpg 1222w, https:\/\/solardrone.es\/wp-content\/uploads\/2024\/03\/Benchmark_OK-300x154.jpg 300w, https:\/\/solardrone.es\/wp-content\/uploads\/2024\/03\/Benchmark_OK-1024x527.jpg 1024w, https:\/\/solardrone.es\/wp-content\/uploads\/2024\/03\/Benchmark_OK-768x395.jpg 768w\" sizes=\"(max-width: 1222px) 100vw, 1222px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-185d0d11 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"185d0d11\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-4e78a9dd\" data-id=\"4e78a9dd\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78702a9 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"78702a9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Una semplice correzione grazie alla termografia fotovoltaica\n<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52037c6 elementor-widget elementor-widget-text-editor\" data-id=\"52037c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"color: #333333;\">Grazie alla termografia fotovoltaica con droni, genera rapporti correttivi e PDF\/Excel in un solo clic. Condividi con i tecnici dell&#8217;impianto grazie alla nostra app mobile che funziona sul campo. <\/span><\/p>\n<p><span style=\"color: #333333;\">Fai il correctrive in 3 semplici passi: analizza, filtra e condividi.<\/span><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6639cae elementor-widget elementor-widget-html\" data-id=\"6639cae\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- Google Calendar Appointment Scheduling begin -->\n<div style=\"display: flex; justify-content: center; margin: 0px 0;\">\n  <link href=\"https:\/\/calendar.google.com\/calendar\/scheduling-button-script.css\" rel=\"stylesheet\">\n  <script src=\"https:\/\/calendar.google.com\/calendar\/scheduling-button-script.js\" async=\"\"><\/script>\n  <script>\n  (function() {\n    var target = document.currentScript;\n    window.addEventListener('load', function() {\n      calendar.schedulingButton.load({\n        url: 'https:\/\/calendar.google.com\/calendar\/appointments\/schedules\/AcZssZ1OM0jl_x3X0YiMRZtN0IyT1RGRs0iAP6coJgkhSx1CwtNHpjAYAcxlENEgtgoC44TADcXH6l7p?gv=true',\n        color: '#3636b6',\n        label: 'AGENDA TU DEMO',\n        target,\n      });\n    });\n  })();\n  <\/script>\n<\/div>\n<!-- end Google Calendar Appointment Scheduling -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-154998ea\" data-id=\"154998ea\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7371e7a elementor-widget elementor-widget-image\" data-id=\"7371e7a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"718\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2024\/01\/actuaciones-1024x919.png\" class=\"attachment-large size-large wp-image-6409\" alt=\"\" srcset=\"https:\/\/solardrone.es\/wp-content\/uploads\/2024\/01\/actuaciones-1024x919.png 1024w, https:\/\/solardrone.es\/wp-content\/uploads\/2024\/01\/actuaciones-300x269.png 300w, https:\/\/solardrone.es\/wp-content\/uploads\/2024\/01\/actuaciones-768x689.png 768w, https:\/\/solardrone.es\/wp-content\/uploads\/2024\/01\/actuaciones.png 1304w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-424b592f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"424b592f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4dc51e32\" data-id=\"4dc51e32\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18a35a64 elementor-widget elementor-widget-video\" data-id=\"18a35a64\" data-element_type=\"widget\" data-settings=\"{&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/solardrone.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/casos-de-exito.jpg&quot;,&quot;id&quot;:665,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;lightbox&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-lightbox\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;hosted&quot;,&quot;url&quot;:&quot;https:\\\/\\\/solardrone.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Solardrone.mp4&quot;,&quot;autoplay&quot;:&quot;&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-18a35a64&quot;,&quot;entranceAnimation&quot;:&quot;&quot;,&quot;entranceAnimation_tablet&quot;:&quot;&quot;,&quot;entranceAnimation_mobile&quot;:&quot;&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;},&quot;videoParams&quot;:{&quot;controls&quot;:&quot;&quot;,&quot;preload&quot;:&quot;metadata&quot;,&quot;controlsList&quot;:&quot;nodownload&quot;}}\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJob3N0ZWQiLCJ1cmwiOiJodHRwczpcL1wvc29sYXJkcm9uZS5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDdcL1NvbGFyZHJvbmUubXA0IiwiYXV0b3BsYXkiOiIiLCJtb2RhbE9wdGlvbnMiOnsiaWQiOiJlbGVtZW50b3ItbGlnaHRib3gtMThhMzVhNjQiLCJlbnRyYW5jZUFuaW1hdGlvbiI6IiIsImVudHJhbmNlQW5pbWF0aW9uX3RhYmxldCI6IiIsImVudHJhbmNlQW5pbWF0aW9uX21vYmlsZSI6IiIsInZpZGVvQXNwZWN0UmF0aW8iOiIxNjkifSwidmlkZW9QYXJhbXMiOnsiY29udHJvbHMiOiIiLCJwcmVsb2FkIjoibWV0YWRhdGEiLCJjb250cm9sc0xpc3QiOiJub2Rvd25sb2FkIn19\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"479\" src=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/07\/casos-de-exito.jpg\" class=\"attachment-full size-full wp-image-665\" alt=\"\" srcset=\"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/07\/casos-de-exito.jpg 640w, https:\/\/solardrone.es\/wp-content\/uploads\/2023\/07\/casos-de-exito-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Riproduci video\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Riproduci video<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5dd14aaf fondodegradado\" data-id=\"5dd14aaf\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-219965e elementor-widget elementor-widget-heading\" data-id=\"219965e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">STORIE DI SUCCESSO<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad2b6e7 elementor-widget__width-inherit elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"ad2b6e7\" data-element_type=\"widget\" data-settings=\"{&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\"Individuare un problema \u00e8 facile, il difficile \u00e8 spiegarlo. Questo \u00e8 il valore distintivo di Solardrone\".<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/solardrone.es\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" alt=\"Victor Mart\u00ednez  \">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Victor Mart\u00ednez  <\/span><span class=\"elementor-testimonial__title\">O&amp;M ENGIE<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\"Il team di Solardrone ha sviluppato un prodotto unico nel settore... Strumenti come MAE (Moduli Fuori Equivalenti) mostrano informazioni molto chiare sul degrado dei moduli. Queste informazioni sono molto utili per avere dati oggettivi sul tasso di deterioramento dei moduli, il che ci permette di dare ulteriori garanzie ai nostri clienti\".<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/solardrone.es\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" alt=\"Juan Manuel Jacob\u00e9\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Juan Manuel Jacob\u00e9<\/span><span class=\"elementor-testimonial__title\">Ingeteam  <\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\"Siamo clienti di Solardrone dal 2017... la loro piattaforma web ha un parametro che ci piace molto: il MAE (Moduli Off Equivalenti) che ci rivela rapidamente la priorit\u00e0 che le nostre azioni dovrebbero seguire in base al loro impatto sul Performance Ratio dell'impianto\".<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/solardrone.es\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" alt=\"Joan Momp\u00f3\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Joan Momp\u00f3<\/span><span class=\"elementor-testimonial__title\">VEOLIA<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\"Solardrone ci aiuta a vendere molto del nostro modo di lavorare e si adatta perfettamente a noi. Per gestire cos\u00ec tanti impianti dobbiamo essere ben organizzati\".<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/solardrone.es\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" alt=\"VEOLIA  \">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">VEOLIA  <\/span><span class=\"elementor-testimonial__title\">Rinnovabili Spagna<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>Abbiamo rilevato il 50% di problemi in pi\u00f9 nel nostro impianto rispetto a un altro fornitore, il che generer\u00e0 80.000 euro in pi\u00f9 all'anno nei prossimi anni nel nostro impianto.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Anonimo<\/span><span class=\"elementor-testimonial__title\">Manager O&amp;M in Spagna<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Precedente<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Successivo<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La tranquillit\u00e0 di avere ogni modulo sotto controllo Termografia fotovoltaica con i droni Volo + piattaforma web + AI. Termografia con droni per rilevare il 100% dei difetti nei moduli fotovoltaici e sapere in meno di 1 minuto come intervenire affinch\u00e9 il tuo impianto generi pi\u00f9 energia. I leader del settore utilizzano gi\u00e0 la termografia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":8042,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-7787","page","type-page","status-publish","hentry"],"rankMath":{"parentDomain":"solardrone.es","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"L&#039;immagine in evidenza dovrebbe essere di almeno 200 x 200 pixel per essere ripresa da Facebook e altri siti di social media.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"termografia-fotovoltaica-con-i-droni","permalinkFormat":"https:\/\/solardrone.es\/it\/servizi\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/solardrone.es\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"Termografia fotovoltaica con i droni | Solardrone  ","description":"Termografia fotovoltaica con i droni. Volo + piattaforma web + AI. \u2713 Prolunga la vita utile dei tuoi impianti fotovoltaici controllando le condizioni dei moduli.  ","focusKeywords":"termografia fotovoltaica,termografia fotovoltaica con droni,termografia fotovoltaica con droni,termografia fotovoltaica con droni","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"nome utente","primaryTerm":0,"authorName":"admin","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":false,"hasBreadcrumb":false},"homeUrl":"https:\/\/solardrone.es\/it\/","objectID":7787,"objectType":"post","locale":"it","localeFull":"it_IT","overlayImages":{"play":{"name":"Icona di riproduzione","url":"https:\/\/solardrone.es\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/var\/www\/vhosts\/solardrone.es\/httpdocs\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Icona GIF","url":"https:\/\/solardrone.es\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/var\/www\/vhosts\/solardrone.es\/httpdocs\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/solardrone.es\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/social-placeholder.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fsolardrone.es%2Fit%2F&r=https%3A%2F%2Fsolardrone.es%2Fit%2Fwp-json%2Fwp%2Fv2%2Fpages%2F7787%3Fnonce%3D3397ffb9e8","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/solardrone.es\/wp-content\/uploads\/2023\/06\/Solardrone-favicon-1-150x150.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Aggiorna","trendsPreviewImage":"https:\/\/solardrone.es\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/solardrone.es\/it\/wp-json\/wp\/v2\/pages\/7787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solardrone.es\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solardrone.es\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solardrone.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solardrone.es\/it\/wp-json\/wp\/v2\/comments?post=7787"}],"version-history":[{"count":4,"href":"https:\/\/solardrone.es\/it\/wp-json\/wp\/v2\/pages\/7787\/revisions"}],"predecessor-version":[{"id":8148,"href":"https:\/\/solardrone.es\/it\/wp-json\/wp\/v2\/pages\/7787\/revisions\/8148"}],"up":[{"embeddable":true,"href":"https:\/\/solardrone.es\/it\/wp-json\/wp\/v2\/pages\/8042"}],"wp:attachment":[{"href":"https:\/\/solardrone.es\/it\/wp-json\/wp\/v2\/media?parent=7787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}